{"id":3155,"date":"2021-10-27T13:37:26","date_gmt":"2021-10-27T11:37:26","guid":{"rendered":"https:\/\/laborest.site\/neuropatia-diabetica-uninsidiosa-complicanza\/"},"modified":"2024-06-21T13:13:16","modified_gmt":"2024-06-21T11:13:16","slug":"neuropatia-diabetica-uninsidiosa-complicanza","status":"publish","type":"post","link":"https:\/\/laborest.com\/it\/neuropatia-diabetica-uninsidiosa-complicanza\/","title":{"rendered":"Neuropatia diabetica, un\u2019insidiosa complicanza"},"content":{"rendered":"<p>Non \u00e8 ancora tenuta abbastanza in considerazione, eppure la <strong>neuropatia diabetica<\/strong> \u00e8 una delle complicanze pi\u00f9 frequenti del diabete.<\/p>\n<ul>\n<li>Nel diabete di tipo 1 il problema, quando colpisce prevalentemente gli arti, si manifesta in almeno il 20% dei casi dopo vent\u2019anni di malattia.<\/li>\n<li>Nel diabete di tipo 2 l\u2019incidenza raggiunge il 50% dopo soli 10 anni di malattia.<\/li>\n<\/ul>\n<p>A lungo andare il danneggiamento dei nervi causato dal diabete pu\u00f2 comportare gravi forme di disabilit\u00e0.<\/p>\n<h4><strong>I vari tipi di neuropatia diabetica<\/strong><\/h4>\n<p>Il primo tipo, detto <strong>neuropatia periferica<\/strong>, colpisce tipicamente i piedi, le gambe ma anche le mani o le braccia. Si manifesta con bruciori, formicolii, intorpidimento, insensibilit\u00e0 al tatto fino al dolore. Non mancano le espressioni a carico dell\u2019apparato motorio: anche la funzionalit\u00e0 muscolare viene danneggiata cos\u00ec come l\u2019equilibrio, aprendo la strada al rischio di cadute. Esiste per\u00f2 anche la <strong>neuropatia autonomica<\/strong> che va a compromettere gli organi viscerali come l\u2019intestino con sintomi estremamente disturbanti (diarree, problemi digestivi, disturbi della motilit\u00e0 gastrica), ma anche il cuore (aritmie, ipertensione), la vescica (incontinenza), gli organi sessuali (disfunzione erettile).<\/p>\n<p>A volte si nota un anomalo aumento della sudorazione. E spesso, a fronte di questo lungo corteo di complicazioni che peggiorano la qualit\u00e0 di vita, subentra l\u2019ansia, o si scatena una forma depressiva. Un insieme di sintomi che dovrebbero far risuonare un campanello d\u2019allarme: purtroppo, per\u00f2, sono sintomi aspecifici che possono riguardare un gran numero di altre malattie.<\/p>\n<h4><strong>Cause della neuropatia diabetica <\/strong><\/h4>\n<p>I meccanismi patogenetici all\u2019origine della neuropatia diabetica sono molteplici, di norma riconducibili allo stress metabolico legato all\u2019iperglicemia o anche alla sindrome metabolica tra i cui criteri diagnostici sono presenti l\u2019alterazione della glicemia a digiuno o l\u2019insulinoresistenza. Troppi zuccheri nel sangue sono tossici per i nervi che vengono sottoposti a un continuo bombardamento ossidativo, il tutto peggiorato dalla riduzione del flusso sanguigno nei piccoli capillari (microangiopatia) conseguente al diabete. La mancanza di ossigeno (ipossia) logora ulteriormente la funzionalit\u00e0 delle fibre nervose. E a peggiorare il quadro subentra l\u2019infiammazione.<\/p>\n<h4><strong>Le strategie da mettere in atto<\/strong><\/h4>\n<p>Non esiste un farmaco specifico per la neuropatia diabetica. Esiste un buon controllo del diabete, che comporta una serie di approcci, prima ancora che farmacologici, relativi agli stili di vita. Ci\u00f2 significa fare regolarmente attivit\u00e0 fisica e prestare attenzione alla dieta: alcol, dolci, troppi carboidrati e grassi concorrono a peggiorare il problema. Anche il fumo di sigaretta danneggia le fibre neuronali.<\/p>\n<h4><strong>L\u2019Acido \u03b1-Lipoico al centro degli studi<\/strong><\/h4>\n<p>Quando si parla di neuropatia diabetica una delle sostanze pi\u00f9 studiate \u00e8 l\u2019<strong>Acido \u03b1-Lipoico<\/strong>, per la sua partecipazione al metabolismo energetico dell\u2019organismo. \u00c8 presente naturalmente nel nostro corpo, ma viene assunto anche attraverso la dieta e, se del caso, attraverso integratori alimentari. Se ne parla da tempo e, a supporto della sua azione positiva nel diabete, sono stati pubblicati numerosi studi e metanalisi. In particolare, l\u2019<strong>Acido \u03b1-Lipoico<\/strong> potrebbe contribuire a contenere i danni neurologici che, come abbiamo visto, spesso si presentano durante la storia naturale del diabete, e i corrispettivi sintomi come i deficit di sensibilit\u00e0, formicolii, bruciori o dolore. Diversi studi gli attribuiscono un effetto antiossidante e antinfiammatorio e, secondo altre ricerche, pu\u00f2 migliorare la circolazione a livello dei piccoli vasi sanguigni che irrorano il sistema nervoso periferico. In pi\u00f9, l\u2019<strong>Acido \u03b1-Lipoico<\/strong> ha mostrato interessanti propriet\u00e0 sul metabolismo degli zuccheri, ovvero sembra in grado di coadiuvare il mantenimento dei livelli di glicemia all\u2019interno dei giusti standard.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong style=\"font-size: 14px;\">Bibliografia<\/strong><\/p>\n<p><span style=\"font-size: 14px;\">1. Bax G. La neuropatia diabetica: l\u2019approccio critico e clinico al problema. MeDia 2014;14:81-7.<br \/>\n2. Bax G. Giornale Italiano di diabetologia e metabolismo 2018; 38:115-126.<br \/>\n3. Pop-Busui R, Boulton AJ, Feldman EL, et al. Diabetic neuropathy: a position statement by the American Diabetes Association. Diabetes Care. 2017;40(1):136\u2013154<br \/>\n4. National Institute of Diabetes and Digestive and Kidney Diseases (NIDDK), What is Diabetic Neuropathy. 2018<br \/>\n5. Albers JW, Pop-Busui R. Diabetic neuropathy: mechanisms, emerging treatments, and subtypes. Curr Neurol Neurosci Rep. 2014; 14 (8): 473<br \/>\n6. Tentolouris N. et al. Standard and emerging treatment options for diabetic neuropathy. Curr Pharm Des. 2014;20(22):3689-704<br \/>\n7. Packer L et al. Molecular aspects of lipoic acid in the prevention of diabetes complications. Nutrition 2001; 17: 888-895<br \/>\n8. Stevens MJ et al. Effects of DL-alpha-lipoic acid on peripheral nerve conduction, blood flow, energy metabolism, and oxidative stress in experimental diabetic neuropathy, Diabetes 2000 Jun; 49(6): 1006-1015<br \/>\n<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Non \u00e8 ancora tenuta abbastanza in considerazione, eppure la neuropatia diabetica \u00e8 una delle complicanze pi\u00f9 frequenti del diabete. Nel diabete di tipo 1 il problema, quando colpisce prevalentemente gli arti, si manifesta in almeno il 20% dei casi dopo vent\u2019anni di malattia. Nel diabete di tipo 2 l\u2019incidenza raggiunge il 50% dopo soli 10 anni di malattia. A lungo andare il danneggiamento dei nervi causato dal diabete pu\u00f2 comportare gravi forme di disabilit\u00e0. I vari tipi di neuropatia diabetica Il primo tipo, detto neuropatia periferica, colpisce tipicamente i piedi, le gambe ma anche le mani o le braccia. Si manifesta con bruciori, formicolii, intorpidimento, insensibilit\u00e0 al tatto fino al dolore. Non mancano le espressioni a carico dell\u2019apparato motorio: anche la funzionalit\u00e0 muscolare viene danneggiata cos\u00ec come l\u2019equilibrio, aprendo la strada al rischio di cadute. Esiste per\u00f2 anche la neuropatia autonomica che va a compromettere gli organi viscerali come l\u2019intestino con sintomi estremamente disturbanti (diarree, problemi digestivi, disturbi della motilit\u00e0 gastrica), ma anche il cuore (aritmie, ipertensione), la vescica (incontinenza), gli organi sessuali (disfunzione erettile). A volte si nota un anomalo aumento della sudorazione. E spesso, a fronte di questo lungo corteo di complicazioni che peggiorano la qualit\u00e0 di vita, subentra l\u2019ansia, o si scatena una forma depressiva. Un insieme di sintomi che dovrebbero far risuonare un campanello d\u2019allarme: purtroppo, per\u00f2, sono sintomi aspecifici che possono riguardare un gran numero di altre malattie. Cause della neuropatia diabetica I meccanismi patogenetici all\u2019origine della neuropatia diabetica sono molteplici, di norma riconducibili allo stress metabolico legato all\u2019iperglicemia o anche alla sindrome metabolica tra i cui criteri diagnostici sono presenti l\u2019alterazione della glicemia a digiuno o l\u2019insulinoresistenza. Troppi zuccheri nel sangue sono tossici per i nervi che vengono sottoposti a un continuo bombardamento ossidativo, il tutto peggiorato dalla riduzione del flusso sanguigno nei piccoli capillari (microangiopatia) conseguente al diabete. La mancanza di ossigeno (ipossia) logora ulteriormente la funzionalit\u00e0 delle fibre nervose. E a peggiorare il quadro subentra l\u2019infiammazione. Le strategie da mettere in atto Non esiste un farmaco specifico per la neuropatia diabetica. Esiste un buon controllo del diabete, che comporta una serie di approcci, prima ancora che farmacologici, relativi agli stili di vita. Ci\u00f2 significa fare regolarmente attivit\u00e0 fisica e prestare attenzione alla dieta: alcol, dolci, troppi carboidrati e grassi concorrono a peggiorare il problema. Anche il fumo di sigaretta danneggia le fibre neuronali. L\u2019Acido \u03b1-Lipoico al centro degli studi Quando si parla di neuropatia diabetica una delle sostanze pi\u00f9 studiate \u00e8 l\u2019Acido \u03b1-Lipoico, per la sua partecipazione al metabolismo energetico dell\u2019organismo. \u00c8 presente naturalmente nel nostro corpo, ma viene assunto anche attraverso la dieta e, se del caso, attraverso integratori alimentari. Se ne parla da tempo e, a supporto della sua azione positiva nel diabete, sono stati pubblicati numerosi studi e metanalisi. In particolare, l\u2019Acido \u03b1-Lipoico potrebbe contribuire a contenere i danni neurologici che, come abbiamo visto, spesso si presentano durante la storia naturale del diabete, e i corrispettivi sintomi come i deficit di sensibilit\u00e0, formicolii, bruciori o dolore. Diversi studi gli attribuiscono un effetto antiossidante e antinfiammatorio e, secondo altre ricerche, pu\u00f2 migliorare la circolazione a livello dei piccoli vasi sanguigni che irrorano il sistema nervoso periferico. In pi\u00f9, l\u2019Acido \u03b1-Lipoico ha mostrato interessanti propriet\u00e0 sul metabolismo degli zuccheri, ovvero sembra in grado di coadiuvare il mantenimento dei livelli di glicemia all\u2019interno dei giusti standard. &nbsp; &nbsp; Bibliografia 1. Bax G. La neuropatia diabetica: l\u2019approccio critico e clinico al problema. MeDia 2014;14:81-7. 2. Bax G. Giornale Italiano di diabetologia e metabolismo 2018; 38:115-126. 3. Pop-Busui R, Boulton AJ, Feldman EL, et al. Diabetic neuropathy: a position statement by the American Diabetes Association. Diabetes Care. 2017;40(1):136\u2013154 4. National Institute of Diabetes and Digestive and Kidney Diseases (NIDDK), What is Diabetic Neuropathy. 2018 5. Albers JW, Pop-Busui R. Diabetic neuropathy: mechanisms, emerging treatments, and subtypes. Curr Neurol Neurosci Rep. 2014; 14 (8): 473 6. Tentolouris N. et al. Standard and emerging treatment options for diabetic neuropathy. Curr Pharm Des. 2014;20(22):3689-704 7. Packer L et al. Molecular aspects of lipoic acid in the prevention of diabetes complications. Nutrition 2001; 17: 888-895 8. Stevens MJ et al. Effects of DL-alpha-lipoic acid on peripheral nerve conduction, blood flow, energy metabolism, and oxidative stress in experimental diabetic neuropathy, Diabetes 2000 Jun; 49(6): 1006-1015<\/p>\n","protected":false},"author":1,"featured_media":3156,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[117],"tags":[],"class_list":["post-3155","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-benessere-adulto"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Neuropatia diabetica, un\u2019insidiosa complicanza - Laborest<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/laborest.com\/it\/neuropatia-diabetica-uninsidiosa-complicanza\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Neuropatia diabetica, un\u2019insidiosa complicanza - Laborest\" \/>\n<meta property=\"og:description\" content=\"Non \u00e8 ancora tenuta abbastanza in considerazione, eppure la neuropatia diabetica \u00e8 una delle complicanze pi\u00f9 frequenti del diabete. Nel diabete di tipo 1 il problema, quando colpisce prevalentemente gli arti, si manifesta in almeno il 20% dei casi dopo vent\u2019anni di malattia. Nel diabete di tipo 2 l\u2019incidenza raggiunge il 50% dopo soli 10 anni di malattia. A lungo andare il danneggiamento dei nervi causato dal diabete pu\u00f2 comportare gravi forme di disabilit\u00e0. I vari tipi di neuropatia diabetica Il primo tipo, detto neuropatia periferica, colpisce tipicamente i piedi, le gambe ma anche le mani o le braccia. Si manifesta con bruciori, formicolii, intorpidimento, insensibilit\u00e0 al tatto fino al dolore. Non mancano le espressioni a carico dell\u2019apparato motorio: anche la funzionalit\u00e0 muscolare viene danneggiata cos\u00ec come l\u2019equilibrio, aprendo la strada al rischio di cadute. Esiste per\u00f2 anche la neuropatia autonomica che va a compromettere gli organi viscerali come l\u2019intestino con sintomi estremamente disturbanti (diarree, problemi digestivi, disturbi della motilit\u00e0 gastrica), ma anche il cuore (aritmie, ipertensione), la vescica (incontinenza), gli organi sessuali (disfunzione erettile). A volte si nota un anomalo aumento della sudorazione. E spesso, a fronte di questo lungo corteo di complicazioni che peggiorano la qualit\u00e0 di vita, subentra l\u2019ansia, o si scatena una forma depressiva. Un insieme di sintomi che dovrebbero far risuonare un campanello d\u2019allarme: purtroppo, per\u00f2, sono sintomi aspecifici che possono riguardare un gran numero di altre malattie. Cause della neuropatia diabetica I meccanismi patogenetici all\u2019origine della neuropatia diabetica sono molteplici, di norma riconducibili allo stress metabolico legato all\u2019iperglicemia o anche alla sindrome metabolica tra i cui criteri diagnostici sono presenti l\u2019alterazione della glicemia a digiuno o l\u2019insulinoresistenza. Troppi zuccheri nel sangue sono tossici per i nervi che vengono sottoposti a un continuo bombardamento ossidativo, il tutto peggiorato dalla riduzione del flusso sanguigno nei piccoli capillari (microangiopatia) conseguente al diabete. La mancanza di ossigeno (ipossia) logora ulteriormente la funzionalit\u00e0 delle fibre nervose. E a peggiorare il quadro subentra l\u2019infiammazione. Le strategie da mettere in atto Non esiste un farmaco specifico per la neuropatia diabetica. Esiste un buon controllo del diabete, che comporta una serie di approcci, prima ancora che farmacologici, relativi agli stili di vita. Ci\u00f2 significa fare regolarmente attivit\u00e0 fisica e prestare attenzione alla dieta: alcol, dolci, troppi carboidrati e grassi concorrono a peggiorare il problema. Anche il fumo di sigaretta danneggia le fibre neuronali. L\u2019Acido \u03b1-Lipoico al centro degli studi Quando si parla di neuropatia diabetica una delle sostanze pi\u00f9 studiate \u00e8 l\u2019Acido \u03b1-Lipoico, per la sua partecipazione al metabolismo energetico dell\u2019organismo. \u00c8 presente naturalmente nel nostro corpo, ma viene assunto anche attraverso la dieta e, se del caso, attraverso integratori alimentari. Se ne parla da tempo e, a supporto della sua azione positiva nel diabete, sono stati pubblicati numerosi studi e metanalisi. In particolare, l\u2019Acido \u03b1-Lipoico potrebbe contribuire a contenere i danni neurologici che, come abbiamo visto, spesso si presentano durante la storia naturale del diabete, e i corrispettivi sintomi come i deficit di sensibilit\u00e0, formicolii, bruciori o dolore. Diversi studi gli attribuiscono un effetto antiossidante e antinfiammatorio e, secondo altre ricerche, pu\u00f2 migliorare la circolazione a livello dei piccoli vasi sanguigni che irrorano il sistema nervoso periferico. In pi\u00f9, l\u2019Acido \u03b1-Lipoico ha mostrato interessanti propriet\u00e0 sul metabolismo degli zuccheri, ovvero sembra in grado di coadiuvare il mantenimento dei livelli di glicemia all\u2019interno dei giusti standard. &nbsp; &nbsp; Bibliografia 1. Bax G. La neuropatia diabetica: l\u2019approccio critico e clinico al problema. MeDia 2014;14:81-7. 2. Bax G. Giornale Italiano di diabetologia e metabolismo 2018; 38:115-126. 3. Pop-Busui R, Boulton AJ, Feldman EL, et al. Diabetic neuropathy: a position statement by the American Diabetes Association. Diabetes Care. 2017;40(1):136\u2013154 4. National Institute of Diabetes and Digestive and Kidney Diseases (NIDDK), What is Diabetic Neuropathy. 2018 5. Albers JW, Pop-Busui R. Diabetic neuropathy: mechanisms, emerging treatments, and subtypes. Curr Neurol Neurosci Rep. 2014; 14 (8): 473 6. Tentolouris N. et al. Standard and emerging treatment options for diabetic neuropathy. Curr Pharm Des. 2014;20(22):3689-704 7. Packer L et al. Molecular aspects of lipoic acid in the prevention of diabetes complications. Nutrition 2001; 17: 888-895 8. Stevens MJ et al. Effects of DL-alpha-lipoic acid on peripheral nerve conduction, blood flow, energy metabolism, and oxidative stress in experimental diabetic neuropathy, Diabetes 2000 Jun; 49(6): 1006-1015\" \/>\n<meta property=\"og:url\" content=\"https:\/\/laborest.com\/it\/neuropatia-diabetica-uninsidiosa-complicanza\/\" \/>\n<meta property=\"og:site_name\" content=\"Laborest\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/LaborestItalia\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-27T11:37:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-21T11:13:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/laborest.com\/wp-content\/uploads\/2024\/06\/neuropatia-diabetica-laboret-blog.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"886\" \/>\n\t<meta property=\"og:image:height\" content=\"886\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Laborest\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Laborest\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/laborest.com\\\/it\\\/neuropatia-diabetica-uninsidiosa-complicanza\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/laborest.com\\\/it\\\/neuropatia-diabetica-uninsidiosa-complicanza\\\/\"},\"author\":{\"name\":\"Laborest\",\"@id\":\"https:\\\/\\\/laborest.com\\\/it\\\/#\\\/schema\\\/person\\\/7a40cd25159b49425639169737f7b7bf\"},\"headline\":\"Neuropatia diabetica, un\u2019insidiosa complicanza\",\"datePublished\":\"2021-10-27T11:37:26+00:00\",\"dateModified\":\"2024-06-21T11:13:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/laborest.com\\\/it\\\/neuropatia-diabetica-uninsidiosa-complicanza\\\/\"},\"wordCount\":702,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/laborest.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/laborest.com\\\/it\\\/neuropatia-diabetica-uninsidiosa-complicanza\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/laborest.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/neuropatia-diabetica-laboret-blog.jpg\",\"articleSection\":[\"Benessere dell'adulto\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/laborest.com\\\/it\\\/neuropatia-diabetica-uninsidiosa-complicanza\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/laborest.com\\\/it\\\/neuropatia-diabetica-uninsidiosa-complicanza\\\/\",\"url\":\"https:\\\/\\\/laborest.com\\\/it\\\/neuropatia-diabetica-uninsidiosa-complicanza\\\/\",\"name\":\"Neuropatia diabetica, un\u2019insidiosa complicanza - Laborest\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/laborest.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/laborest.com\\\/it\\\/neuropatia-diabetica-uninsidiosa-complicanza\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/laborest.com\\\/it\\\/neuropatia-diabetica-uninsidiosa-complicanza\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/laborest.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/neuropatia-diabetica-laboret-blog.jpg\",\"datePublished\":\"2021-10-27T11:37:26+00:00\",\"dateModified\":\"2024-06-21T11:13:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/laborest.com\\\/it\\\/neuropatia-diabetica-uninsidiosa-complicanza\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/laborest.com\\\/it\\\/neuropatia-diabetica-uninsidiosa-complicanza\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/laborest.com\\\/it\\\/neuropatia-diabetica-uninsidiosa-complicanza\\\/#primaryimage\",\"url\":\"https:\\\/\\\/laborest.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/neuropatia-diabetica-laboret-blog.jpg\",\"contentUrl\":\"https:\\\/\\\/laborest.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/neuropatia-diabetica-laboret-blog.jpg\",\"width\":886,\"height\":886,\"caption\":\"Neuropatia diabetica\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/laborest.com\\\/it\\\/neuropatia-diabetica-uninsidiosa-complicanza\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/laborest.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Neuropatia diabetica, un\u2019insidiosa complicanza\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/laborest.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/laborest.com\\\/it\\\/\",\"name\":\"Laborest\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/laborest.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/laborest.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/laborest.com\\\/it\\\/#organization\",\"name\":\"Laborest\",\"url\":\"https:\\\/\\\/laborest.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/laborest.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/laborest.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/logo.svg\",\"contentUrl\":\"https:\\\/\\\/laborest.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/logo.svg\",\"width\":260,\"height\":49,\"caption\":\"Laborest\"},\"image\":{\"@id\":\"https:\\\/\\\/laborest.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/LaborestItalia\\\/\",\"https:\\\/\\\/it.linkedin.com\\\/showcase\\\/laborest-italia-spa\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/laborest.com\\\/it\\\/#\\\/schema\\\/person\\\/7a40cd25159b49425639169737f7b7bf\",\"name\":\"Laborest\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/96b68193558e92f75b01e403ecd8fcffe514214495130989206f71dcd49afc8c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/96b68193558e92f75b01e403ecd8fcffe514214495130989206f71dcd49afc8c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/96b68193558e92f75b01e403ecd8fcffe514214495130989206f71dcd49afc8c?s=96&d=mm&r=g\",\"caption\":\"Laborest\"},\"sameAs\":[\"https:\\\/\\\/laborest.com\"],\"url\":\"https:\\\/\\\/laborest.com\\\/it\\\/author\\\/laborestadmin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Neuropatia diabetica, un\u2019insidiosa complicanza - Laborest","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/laborest.com\/it\/neuropatia-diabetica-uninsidiosa-complicanza\/","og_locale":"it_IT","og_type":"article","og_title":"Neuropatia diabetica, un\u2019insidiosa complicanza - Laborest","og_description":"Non \u00e8 ancora tenuta abbastanza in considerazione, eppure la neuropatia diabetica \u00e8 una delle complicanze pi\u00f9 frequenti del diabete. Nel diabete di tipo 1 il problema, quando colpisce prevalentemente gli arti, si manifesta in almeno il 20% dei casi dopo vent\u2019anni di malattia. Nel diabete di tipo 2 l\u2019incidenza raggiunge il 50% dopo soli 10 anni di malattia. A lungo andare il danneggiamento dei nervi causato dal diabete pu\u00f2 comportare gravi forme di disabilit\u00e0. I vari tipi di neuropatia diabetica Il primo tipo, detto neuropatia periferica, colpisce tipicamente i piedi, le gambe ma anche le mani o le braccia. Si manifesta con bruciori, formicolii, intorpidimento, insensibilit\u00e0 al tatto fino al dolore. Non mancano le espressioni a carico dell\u2019apparato motorio: anche la funzionalit\u00e0 muscolare viene danneggiata cos\u00ec come l\u2019equilibrio, aprendo la strada al rischio di cadute. Esiste per\u00f2 anche la neuropatia autonomica che va a compromettere gli organi viscerali come l\u2019intestino con sintomi estremamente disturbanti (diarree, problemi digestivi, disturbi della motilit\u00e0 gastrica), ma anche il cuore (aritmie, ipertensione), la vescica (incontinenza), gli organi sessuali (disfunzione erettile). A volte si nota un anomalo aumento della sudorazione. E spesso, a fronte di questo lungo corteo di complicazioni che peggiorano la qualit\u00e0 di vita, subentra l\u2019ansia, o si scatena una forma depressiva. Un insieme di sintomi che dovrebbero far risuonare un campanello d\u2019allarme: purtroppo, per\u00f2, sono sintomi aspecifici che possono riguardare un gran numero di altre malattie. Cause della neuropatia diabetica I meccanismi patogenetici all\u2019origine della neuropatia diabetica sono molteplici, di norma riconducibili allo stress metabolico legato all\u2019iperglicemia o anche alla sindrome metabolica tra i cui criteri diagnostici sono presenti l\u2019alterazione della glicemia a digiuno o l\u2019insulinoresistenza. Troppi zuccheri nel sangue sono tossici per i nervi che vengono sottoposti a un continuo bombardamento ossidativo, il tutto peggiorato dalla riduzione del flusso sanguigno nei piccoli capillari (microangiopatia) conseguente al diabete. La mancanza di ossigeno (ipossia) logora ulteriormente la funzionalit\u00e0 delle fibre nervose. E a peggiorare il quadro subentra l\u2019infiammazione. Le strategie da mettere in atto Non esiste un farmaco specifico per la neuropatia diabetica. Esiste un buon controllo del diabete, che comporta una serie di approcci, prima ancora che farmacologici, relativi agli stili di vita. Ci\u00f2 significa fare regolarmente attivit\u00e0 fisica e prestare attenzione alla dieta: alcol, dolci, troppi carboidrati e grassi concorrono a peggiorare il problema. Anche il fumo di sigaretta danneggia le fibre neuronali. L\u2019Acido \u03b1-Lipoico al centro degli studi Quando si parla di neuropatia diabetica una delle sostanze pi\u00f9 studiate \u00e8 l\u2019Acido \u03b1-Lipoico, per la sua partecipazione al metabolismo energetico dell\u2019organismo. \u00c8 presente naturalmente nel nostro corpo, ma viene assunto anche attraverso la dieta e, se del caso, attraverso integratori alimentari. Se ne parla da tempo e, a supporto della sua azione positiva nel diabete, sono stati pubblicati numerosi studi e metanalisi. In particolare, l\u2019Acido \u03b1-Lipoico potrebbe contribuire a contenere i danni neurologici che, come abbiamo visto, spesso si presentano durante la storia naturale del diabete, e i corrispettivi sintomi come i deficit di sensibilit\u00e0, formicolii, bruciori o dolore. Diversi studi gli attribuiscono un effetto antiossidante e antinfiammatorio e, secondo altre ricerche, pu\u00f2 migliorare la circolazione a livello dei piccoli vasi sanguigni che irrorano il sistema nervoso periferico. In pi\u00f9, l\u2019Acido \u03b1-Lipoico ha mostrato interessanti propriet\u00e0 sul metabolismo degli zuccheri, ovvero sembra in grado di coadiuvare il mantenimento dei livelli di glicemia all\u2019interno dei giusti standard. &nbsp; &nbsp; Bibliografia 1. Bax G. La neuropatia diabetica: l\u2019approccio critico e clinico al problema. MeDia 2014;14:81-7. 2. Bax G. Giornale Italiano di diabetologia e metabolismo 2018; 38:115-126. 3. Pop-Busui R, Boulton AJ, Feldman EL, et al. Diabetic neuropathy: a position statement by the American Diabetes Association. Diabetes Care. 2017;40(1):136\u2013154 4. National Institute of Diabetes and Digestive and Kidney Diseases (NIDDK), What is Diabetic Neuropathy. 2018 5. Albers JW, Pop-Busui R. Diabetic neuropathy: mechanisms, emerging treatments, and subtypes. Curr Neurol Neurosci Rep. 2014; 14 (8): 473 6. Tentolouris N. et al. Standard and emerging treatment options for diabetic neuropathy. Curr Pharm Des. 2014;20(22):3689-704 7. Packer L et al. Molecular aspects of lipoic acid in the prevention of diabetes complications. Nutrition 2001; 17: 888-895 8. Stevens MJ et al. Effects of DL-alpha-lipoic acid on peripheral nerve conduction, blood flow, energy metabolism, and oxidative stress in experimental diabetic neuropathy, Diabetes 2000 Jun; 49(6): 1006-1015","og_url":"https:\/\/laborest.com\/it\/neuropatia-diabetica-uninsidiosa-complicanza\/","og_site_name":"Laborest","article_publisher":"https:\/\/www.facebook.com\/LaborestItalia\/","article_published_time":"2021-10-27T11:37:26+00:00","article_modified_time":"2024-06-21T11:13:16+00:00","og_image":[{"width":886,"height":886,"url":"https:\/\/laborest.com\/wp-content\/uploads\/2024\/06\/neuropatia-diabetica-laboret-blog.jpg","type":"image\/jpeg"}],"author":"Laborest","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Laborest","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/laborest.com\/it\/neuropatia-diabetica-uninsidiosa-complicanza\/#article","isPartOf":{"@id":"https:\/\/laborest.com\/it\/neuropatia-diabetica-uninsidiosa-complicanza\/"},"author":{"name":"Laborest","@id":"https:\/\/laborest.com\/it\/#\/schema\/person\/7a40cd25159b49425639169737f7b7bf"},"headline":"Neuropatia diabetica, un\u2019insidiosa complicanza","datePublished":"2021-10-27T11:37:26+00:00","dateModified":"2024-06-21T11:13:16+00:00","mainEntityOfPage":{"@id":"https:\/\/laborest.com\/it\/neuropatia-diabetica-uninsidiosa-complicanza\/"},"wordCount":702,"commentCount":0,"publisher":{"@id":"https:\/\/laborest.com\/it\/#organization"},"image":{"@id":"https:\/\/laborest.com\/it\/neuropatia-diabetica-uninsidiosa-complicanza\/#primaryimage"},"thumbnailUrl":"https:\/\/laborest.com\/wp-content\/uploads\/2024\/06\/neuropatia-diabetica-laboret-blog.jpg","articleSection":["Benessere dell'adulto"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/laborest.com\/it\/neuropatia-diabetica-uninsidiosa-complicanza\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/laborest.com\/it\/neuropatia-diabetica-uninsidiosa-complicanza\/","url":"https:\/\/laborest.com\/it\/neuropatia-diabetica-uninsidiosa-complicanza\/","name":"Neuropatia diabetica, un\u2019insidiosa complicanza - Laborest","isPartOf":{"@id":"https:\/\/laborest.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/laborest.com\/it\/neuropatia-diabetica-uninsidiosa-complicanza\/#primaryimage"},"image":{"@id":"https:\/\/laborest.com\/it\/neuropatia-diabetica-uninsidiosa-complicanza\/#primaryimage"},"thumbnailUrl":"https:\/\/laborest.com\/wp-content\/uploads\/2024\/06\/neuropatia-diabetica-laboret-blog.jpg","datePublished":"2021-10-27T11:37:26+00:00","dateModified":"2024-06-21T11:13:16+00:00","breadcrumb":{"@id":"https:\/\/laborest.com\/it\/neuropatia-diabetica-uninsidiosa-complicanza\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/laborest.com\/it\/neuropatia-diabetica-uninsidiosa-complicanza\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/laborest.com\/it\/neuropatia-diabetica-uninsidiosa-complicanza\/#primaryimage","url":"https:\/\/laborest.com\/wp-content\/uploads\/2024\/06\/neuropatia-diabetica-laboret-blog.jpg","contentUrl":"https:\/\/laborest.com\/wp-content\/uploads\/2024\/06\/neuropatia-diabetica-laboret-blog.jpg","width":886,"height":886,"caption":"Neuropatia diabetica"},{"@type":"BreadcrumbList","@id":"https:\/\/laborest.com\/it\/neuropatia-diabetica-uninsidiosa-complicanza\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/laborest.com\/it\/"},{"@type":"ListItem","position":2,"name":"Neuropatia diabetica, un\u2019insidiosa complicanza"}]},{"@type":"WebSite","@id":"https:\/\/laborest.com\/it\/#website","url":"https:\/\/laborest.com\/it\/","name":"Laborest","description":"","publisher":{"@id":"https:\/\/laborest.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/laborest.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/laborest.com\/it\/#organization","name":"Laborest","url":"https:\/\/laborest.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/laborest.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/laborest.com\/wp-content\/uploads\/2024\/04\/logo.svg","contentUrl":"https:\/\/laborest.com\/wp-content\/uploads\/2024\/04\/logo.svg","width":260,"height":49,"caption":"Laborest"},"image":{"@id":"https:\/\/laborest.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/LaborestItalia\/","https:\/\/it.linkedin.com\/showcase\/laborest-italia-spa\/"]},{"@type":"Person","@id":"https:\/\/laborest.com\/it\/#\/schema\/person\/7a40cd25159b49425639169737f7b7bf","name":"Laborest","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/96b68193558e92f75b01e403ecd8fcffe514214495130989206f71dcd49afc8c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/96b68193558e92f75b01e403ecd8fcffe514214495130989206f71dcd49afc8c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/96b68193558e92f75b01e403ecd8fcffe514214495130989206f71dcd49afc8c?s=96&d=mm&r=g","caption":"Laborest"},"sameAs":["https:\/\/laborest.com"],"url":"https:\/\/laborest.com\/it\/author\/laborestadmin\/"}]}},"_links":{"self":[{"href":"https:\/\/laborest.com\/it\/wp-json\/wp\/v2\/posts\/3155","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laborest.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laborest.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laborest.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/laborest.com\/it\/wp-json\/wp\/v2\/comments?post=3155"}],"version-history":[{"count":0,"href":"https:\/\/laborest.com\/it\/wp-json\/wp\/v2\/posts\/3155\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laborest.com\/it\/wp-json\/wp\/v2\/media\/3156"}],"wp:attachment":[{"href":"https:\/\/laborest.com\/it\/wp-json\/wp\/v2\/media?parent=3155"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laborest.com\/it\/wp-json\/wp\/v2\/categories?post=3155"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laborest.com\/it\/wp-json\/wp\/v2\/tags?post=3155"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}